{"id":19119,"date":"2022-05-20T13:00:23","date_gmt":"2022-05-20T17:00:23","guid":{"rendered":"https:\/\/www.apolinav.cl\/?p=19119"},"modified":"2022-05-20T13:02:29","modified_gmt":"2022-05-20T17:02:29","slug":"academia-politecnica-naval-realiza-ceremonia-militar-en-homenaje-a-las-glorias-navales","status":"publish","type":"post","link":"https:\/\/www.apolinav.cl\/index.php\/academia-politecnica-naval-realiza-ceremonia-militar-en-homenaje-a-las-glorias-navales\/","title":{"rendered":"ACADEMIA POLIT\u00c9CNICA NAVAL REALIZA CEREMONIA MILITAR EN HOMENAJE A LAS GLORIAS NAVALES."},"content":{"rendered":"<p>Vi\u00f1a del Mar. Con motivo de conmemorarse el cent\u00e9simo cuadrag\u00e9simo tercer aniversario del Combate Naval de Iquique y Punta Gruesa, la ma\u00f1ana de este 20 de mayo, la dotaci\u00f3n de la Academia Polit\u00e9cnica Naval form\u00f3 en el patio principal donde se realiz\u00f3 una ceremonia militar interna, con imposici\u00f3n de condecoraciones por a\u00f1os de servicio a Oficiales y Gente de Mar.<\/p>\n<p>La actividad fue presidida por el Director de la A.P.N., Capit\u00e1n de Nav\u00edo Fabi\u00e1n Gonz\u00e1lez, acompa\u00f1ado del Subdirector Administrativo, Jefes de Campus, Decano, Docentes, alumnos, familiares e invitados especiales.<\/p>\n<p>Posterior al izamiento del Pabell\u00f3n Nacional, a los sones de la Banda de M\u00fasicos de la Academia, el Comandante Gonz\u00e1lez efectu\u00f3 el discurso alusivo a los 143\u00b0 aniversario de las Glorias Navales donde expres\u00f3: \u201cComo chilenos y como marinos, debemos aprender a valorar en su justa dimensi\u00f3n, las implicancias de la gesta heroica de mayo de 1879, ya que solo as\u00ed lograremos entender nuestra historia y valorarla como patrimonio de Chile\u201d.<\/p>\n<p>Prosigui\u00f3 diciendo: \u201dEl legado que nos dejaron los H\u00e9roes de Iquique debe seguir siendo un faro que ilumine a nuestra sociedad, la que necesita h\u00e9roes sencillos, a escala humana, que no duden en cumplir con su deber y que sean capaces de darlo todo por defender los intereses de nuestro pa\u00eds. Estoy seguro que aquellos marinos de la Esmeralda y de la Covadonga, al verse enfrentados a tama\u00f1a fuerza desigual, a\u00fan cuando pudieron haberse sentido v\u00edctimas de las circunstancias, no lo hicieron y decidieron adoptar una actitud valiente y proactiva ante la adversidad. El ejemplo del Comandante Arturo Prat y la valiente dotaci\u00f3n de la gloriosa Esmeralda, debe constituir el modelo de valent\u00eda y fortaleza que gu\u00ede siempre a nuestra Armada por los mares del honor y la gloria\u201d.<\/p>\n<p>Terminada la alocuci\u00f3n patri\u00f3tica, se efectu\u00f3 la imposici\u00f3n de medallas por 10, 20 y 30 a\u00f1os de servicio, recibiendo la Condecoraci\u00f3n \u201cAl M\u00e9rito Militar de las Fuerzas Armadas\u201d.<\/p>\n<p>La ceremonia finaliz\u00f3 con el Himno de la Armada el que fue coreado por todos los presentes.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-19119 gallery-columns-3 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/001-8.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/001-8-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/001-8-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/001-8-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/001-8-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/001-8-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/001-8-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/002-7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/002-7-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/002-7-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/002-7-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/002-7-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/002-7-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/002-7-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/003-8.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/003-8-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/003-8-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/003-8-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/003-8-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/003-8-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/003-8-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/004-7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/004-7-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/004-7-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/004-7-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/004-7-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/004-7-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/004-7-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/005-5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/005-5-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/005-5-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/005-5-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/005-5-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/005-5-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/005-5-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/006-6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/006-6-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/006-6-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/006-6-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/006-6-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/006-6-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/006-6-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/008-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/008-3-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/008-3-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/008-3-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/008-3-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/008-3-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/008-3-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/009-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/009-2-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/009-2-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/009-2-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/009-2-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/009-2-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/009-2-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/010.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/010-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/010-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/010-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/010-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/010-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/010-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/011-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/011-2-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/011-2-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/011-2-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/011-2-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/011-2-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/011-2-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/012-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/012-2-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/012-2-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/012-2-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/012-2-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/012-2-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/012-2-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/014-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/014-2-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/014-2-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/014-2-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/014-2-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/014-2-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/014-2-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/015.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/015-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/015-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/015-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/015-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/015-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/015-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/016.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/016-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/016-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/016-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/016-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/016-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/016-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/017.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/017-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/017-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/017-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/017-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/017-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/017-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/018.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/018-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/018-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/018-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/018-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/018-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/018-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/019.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/019-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/019-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/019-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/019-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/019-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/019-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/021.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/021-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/021-300x300.jpg 300w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/021-1024x1024.jpg 1024w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/021-150x150.jpg 150w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/021-1536x1536.jpg 1536w, https:\/\/www.apolinav.cl\/wp-content\/uploads\/2022\/05\/021-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Vi\u00f1a del Mar. Con motivo de conmemorarse el cent\u00e9simo cuadrag\u00e9simo tercer aniversario del Combate Naval de Iquique y Punta Gruesa, la ma\u00f1ana de este 20 de mayo, la dotaci\u00f3n de la Academia Polit\u00e9cnica Naval form\u00f3 en el patio principal donde se realiz\u00f3 una ceremonia militar interna, con imposici\u00f3n de condecoraciones por a\u00f1os de servicio a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19128,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-19119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.apolinav.cl\/index.php\/wp-json\/wp\/v2\/posts\/19119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apolinav.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apolinav.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apolinav.cl\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apolinav.cl\/index.php\/wp-json\/wp\/v2\/comments?post=19119"}],"version-history":[{"count":2,"href":"https:\/\/www.apolinav.cl\/index.php\/wp-json\/wp\/v2\/posts\/19119\/revisions"}],"predecessor-version":[{"id":19139,"href":"https:\/\/www.apolinav.cl\/index.php\/wp-json\/wp\/v2\/posts\/19119\/revisions\/19139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apolinav.cl\/index.php\/wp-json\/wp\/v2\/media\/19128"}],"wp:attachment":[{"href":"https:\/\/www.apolinav.cl\/index.php\/wp-json\/wp\/v2\/media?parent=19119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apolinav.cl\/index.php\/wp-json\/wp\/v2\/categories?post=19119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apolinav.cl\/index.php\/wp-json\/wp\/v2\/tags?post=19119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}